{"id":21801,"date":"2020-09-28T12:49:38","date_gmt":"2020-09-28T10:49:38","guid":{"rendered":"https:\/\/www.alfaforni.com\/?p=21801"},"modified":"2024-04-16T13:04:58","modified_gmt":"2024-04-16T11:04:58","slug":"alfa-forni-presenta-stone-oven-il-forno-a-legna-e-gas-che-rinnova-il-design-delle-cucine-outdoor-piu-esclusive","status":"publish","type":"post","link":"https:\/\/www.alfaforni.com\/it\/alfa-forni-presenta-stone-oven-il-forno-a-legna-e-gas-che-rinnova-il-design-delle-cucine-outdoor-piu-esclusive\/","title":{"rendered":"Alfa Forni presenta STONE OVEN, il forno a legna e gas  che rinnova il design delle cucine outdoor pi\u00f9 esclusive"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h3>La nuova proposta Alfa si rivolge alla grande crescita del mercato outdoor e alle richieste sempre pi\u00f9 esigenti di chi ama la cottura alla fiamma ma ha un\u2019attenzione particolare per i dettagli di stile<\/h3>\n<p>&nbsp;<\/p>\n<p><b><a href=\"https:\/\/www.alfaforni.com\/it\/prodotto\/stone-oven\/\">Stone Oven<\/a><\/b>&nbsp;nasce da un nuovo concept di&nbsp;<strong>Alfa Forni per rispondere alle esigenze di uno dei settori che sta conoscendo la crescita maggiore nell\u2019epoca post-Covid<\/strong>: il mercato delle cucine outdoor si amplia con un prodotto dal design completamente rinnovato grazie all\u2019inedito archetto in acciaio inox frontale. Questo dettaglio di stile, che dona eleganza a un forno solido e potente, \u00e8 il risultato di un raffinato lavoro artigianale di piegatura e levigatura realizzata a mano in Italia dagli operai specializzati Alfa.<\/p>\n<p>&nbsp;<\/p>\n<p>Finiture artigianali si combinano nella nuova proposta Alfa Forni con altissime prestazioni:&nbsp;<b><a href=\"https:\/\/www.alfaforni.com\/it\/prodotto\/stone-oven\/\">Stone Oven non \u00e8 solo design, ma un forno ibrido<\/a><\/b>, utilizzabile quindi sia a legna sia a gas, ideale per cuocere ogni tipo di pietanza &#8211; dalla pizza alla carne, dalle verdure ai dolci. Altra innovazione \u00e8 l\u2019ampio sportello in vetro che, nel caso delle cotture lente, permette di monitorare la camera di cottura senza aprirla, una prerogativa inedita di questo nuovo modello.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1024\" height=\"640\"  src=\"http:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/11\/stone-oven-gas-fired-pizza-oven-alfa-forni.jpg\" class=\"img-responsive wp-image-13625\" srcset=\"https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/11\/stone-oven-gas-fired-pizza-oven-alfa-forni-400x250.jpg 400w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/11\/stone-oven-gas-fired-pizza-oven-alfa-forni-600x375.jpg 600w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/11\/stone-oven-gas-fired-pizza-oven-alfa-forni-800x500.jpg 800w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/11\/stone-oven-gas-fired-pizza-oven-alfa-forni.jpg 1024w\" sizes=\"(max-width: 640px) 100vw, 1024px\" alt=\"\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:7.68%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"1200\" height=\"1200\"  src=\"http:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-gas-connection.jpg\" class=\"img-responsive wp-image-13618\" srcset=\"https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-gas-connection-400x400.jpg 400w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-gas-connection-600x600.jpg 600w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-gas-connection-800x800.jpg 800w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-gas-connection.jpg 1200w\" sizes=\"(max-width: 640px) 100vw, 400px\" alt=\"\"><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:7.68%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"1200\" height=\"1200\"  src=\"http:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-ovens-color.jpg\" class=\"img-responsive wp-image-13606\" srcset=\"https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-ovens-color-400x400.jpg 400w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-ovens-color-600x600.jpg 600w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-ovens-color-800x800.jpg 800w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-ovens-color.jpg 1200w\" sizes=\"(max-width: 640px) 100vw, 400px\" alt=\"\"><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:7.68%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-4 hover-type-none\"><img decoding=\"async\" width=\"1200\" height=\"1200\"  src=\"http:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-made-in-italy.jpg\" class=\"img-responsive wp-image-13600\" srcset=\"https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-made-in-italy-400x400.jpg 400w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-made-in-italy-600x600.jpg 600w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-made-in-italy-800x800.jpg 800w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-made-in-italy.jpg 1200w\" sizes=\"(max-width: 640px) 100vw, 400px\" alt=\"\"><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:7.68%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-5 hover-type-none\"><img decoding=\"async\" width=\"1200\" height=\"1200\"  src=\"http:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-temperature-alfa-forni-500c.jpg\" class=\"img-responsive wp-image-13631\" srcset=\"https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-temperature-alfa-forni-500c-400x400.jpg 400w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-temperature-alfa-forni-500c-600x600.jpg 600w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-temperature-alfa-forni-500c-800x800.jpg 800w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-temperature-alfa-forni-500c.jpg 1200w\" sizes=\"(max-width: 640px) 100vw, 400px\" alt=\"\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top-medium:0px;--awb-padding-bottom-medium:0px;--awb-padding-right-small:0px;--awb-padding-left-small:0px;--awb-margin-top:68px;--awb-background-color:rgba(239,232,226,0);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:40px;--awb-padding-right:20px;--awb-padding-bottom:50px;--awb-padding-left:30px;--awb-padding-top-medium:40px;--awb-padding-right-medium:0px;--awb-padding-bottom-medium:30px;--awb-padding-left-medium:15px;--awb-padding-top-small:30px;--awb-padding-right-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#755847;--awb-bg-color-hover:#755847;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0px;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0px;--awb-spacing-left-medium:3.84%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:0px;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><h2>Vuoi scoprire qual \u00e8 il forno pi\u00f9 adatto alle tue esigenze?<\/h2>\n<\/div><div class=\"sm-text-align-left\" style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button_gradient_top_color:#990521;--button_gradient_bottom_color:#990521;--button_gradient_top_color_hover:var(--awb-color6);--button_gradient_bottom_color_hover:var(--awb-color6);--button_font_size:14px;--button_line_height:17px;--button_padding-top:20px;--button_padding-right:30px;--button_padding-bottom:20px;--button_padding-left:30px;--button_typography-letter-spacing:2px;--button_typography-font-family:&quot;Open Sans&quot;;--button_typography-font-style:normal;--button_typography-font-weight:700;--button_margin-top:-20px;--button_margin-right:45px;\" target=\"_self\" href=\"https:\/\/blog.alfaforni.com\/it\/lp-catalogo-forni-domestici\" rel=\"nofollow noopener\"><i class=\"fa-download fas awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Scarica il nostro catalogo domestico \u203a<\/span><\/a><\/div><div class=\"sm-text-align-left\" style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button_gradient_top_color:#990521;--button_gradient_bottom_color:#990521;--button_gradient_top_color_hover:var(--awb-color6);--button_gradient_bottom_color_hover:var(--awb-color6);--button_font_size:14px;--button_line_height:17px;--button_padding-top:20px;--button_padding-right:30px;--button_padding-bottom:20px;--button_padding-left:30px;--button_typography-letter-spacing:2px;--button_typography-font-family:&quot;Open Sans&quot;;--button_typography-font-style:normal;--button_typography-font-weight:700;--button_margin-top:15px;--button_margin-right:45px;\" target=\"_self\" href=\"https:\/\/pro.alfaforni.com\/it\/scarica-il-catalogo-professionale\/\" rel=\"nofollow noopener\"><i class=\"fa-download fas awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Scarica il nostro catalogo professionale \u203a<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:20px;--awb-padding-right:50px;--awb-padding-bottom:30px;--awb-padding-top-medium:40px;--awb-padding-right-medium:30px;--awb-padding-bottom-medium:30px;--awb-padding-left-medium:30px;--awb-padding-top-small:0px;--awb-padding-right-small:0px;--awb-padding-bottom-small:20px;--awb-padding-left-small:0px;--awb-bg-color:#755847;--awb-bg-color-hover:#755847;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:0px;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:0px;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-6 hover-type-none\"><img decoding=\"async\" width=\"432\" height=\"506\"  src=\"http:\/\/www.alfaforni.com\/wp-content\/uploads\/2022\/09\/anteprima-download-it.png\" class=\"img-responsive wp-image-36449\" srcset=\"https:\/\/www.alfaforni.com\/wp-content\/uploads\/2022\/09\/anteprima-download-it-400x469.png 400w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2022\/09\/anteprima-download-it.png 432w\" sizes=\"(max-width: 640px) 100vw, 432px\" alt=\"\"><\/span><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\"><p>Anche&nbsp;<b><a href=\"https:\/\/www.alfaforni.com\/it\/prodotto\/stone-oven\/\">Stone Oven<\/a><\/b>&nbsp;porta il brevetto Forninox<sup>\u2122<\/sup>&nbsp;che ha reso celebri i prodotti Alfa: il piano di cottura \u00e8 prodotto interamente in-house in materiale refrattario, mentre la camera di cottura semi-professionale in acciaio 441, resistente ed elastico, assicura elevate prestazioni di combustione. L\u2019innovativo sistema di giro fumi riduce il consumo di combustibile ed evita la fastidiosa fuoriuscita di fumo, mentre la cupola \u00e8 verniciata a polvere in 7 stadi per assicurare una maggiore resistenza alle intemperie. I benefici di un prodotto come lo&nbsp;<b><a href=\"https:\/\/www.alfaforni.com\/it\/prodotto\/stone-oven\/\">Stone Oven<\/a><\/b>&nbsp;sono immediati: oltre a rappresentare un elegante complemento d\u2019arredo per la cucina outdoor, il forno \u00e8 pronto per l\u2019uso in soli 30 minuti e consente di invitare a pranzo fino a 20 persone!<\/p>\n<p>\u201c<em>Il mercato si sta evolvendo a una velocit\u00e0 inedita e i nostri prodotti rispondono con proposte sempre pi\u00f9 innovative.&nbsp;<b><a href=\"https:\/\/www.alfaforni.com\/it\/prodotto\/stone-oven\/\">Stone Oven<\/a><\/b>&nbsp;si propone di rinnovare il settore delle cucine outdoor unendo prestazioni, eleganza e comodit\u00e0 d\u2019uso<\/em>\u201d, afferma&nbsp;<strong>Giulia Lauro, Product Marketing Manager<\/strong>.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-7 hover-type-none\"><img decoding=\"async\" width=\"1024\" height=\"640\"  src=\"http:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-boccaforno.jpg\" class=\"img-responsive wp-image-13594\" srcset=\"https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-boccaforno-400x250.jpg 400w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-boccaforno-600x375.jpg 600w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-boccaforno-800x500.jpg 800w, https:\/\/www.alfaforni.com\/wp-content\/uploads\/2019\/05\/stone-oven-alfa-forni-boccaforno.jpg 1024w\" sizes=\"(max-width: 640px) 100vw, 1024px\" alt=\"\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-4\"><p><b><a href=\"https:\/\/www.alfaforni.com\/it\/prodotto\/stone-oven\/\">Alfa Stone Oven<\/a><\/b>&nbsp;\u00e8<strong>&nbsp;disponibile per la vendita a partire dal 1 ottobre 2020<\/strong>.<\/p>\n<p>Per ulteriori informazioni:&nbsp;<b><a href=\"http:\/\/www.alfaforni.com\/\">www.alfaforni.com<\/a><\/b><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":13612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,450],"tags":[],"class_list":["post-21801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-it","category-news-home"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/posts\/21801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/comments?post=21801"}],"version-history":[{"count":1,"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/posts\/21801\/revisions"}],"predecessor-version":[{"id":57506,"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/posts\/21801\/revisions\/57506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/media\/13612"}],"wp:attachment":[{"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/media?parent=21801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/categories?post=21801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alfaforni.com\/it\/wp-json\/wp\/v2\/tags?post=21801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}